{"id":2467,"date":"2019-10-03T11:28:17","date_gmt":"2019-10-03T09:28:17","guid":{"rendered":"https:\/\/labarraca1912.es\/?post_type=product&#038;p=2467"},"modified":"2022-11-21T11:49:44","modified_gmt":"2022-11-21T10:49:44","slug":"sazonador-paella-37g","status":"publish","type":"product","link":"https:\/\/labarraca1912.es\/en\/tienda\/sazonadores\/sazonador-paella-37g\/","title":{"rendered":"Paella Seasoning 37g"},"content":{"rendered":"<p>PAELLA SEASONING - 37G: The Paella Seasoning is a magnificent product to give the ideal flavour to a paella. Thanks to the combination of different types of spices, herbs and condiments, which combined make this seasoning indispensable in the preparation of a paella.<\/p>\n<p><strong>Paella Seasoning:<\/strong> Seasoning composed of a mixture of ground spices; expressly formulated for the elaboration of paellas and rice.<\/p>","protected":false},"excerpt":{"rendered":"<h2><\/h2>\n<blockquote>\n<h2><strong>Paella Seasoning<\/strong> 37g<\/h2>\n<\/blockquote>\n<p>The Paella Seasoning is a magnificent product to give the ideal flavour to a paella. Thanks to the combination of different types of spices, herbs and condiments, which combined make this seasoning indispensable in the preparation of a paella. Seasoning composed of a mixture of ground spices; expressly formulated for the elaboration of paellas and rice.<\/p>\n<h3><a href=\"https:\/\/labarraca1912.es\/en\/fichas-tecnicas\/FT%20SAZONADOR%20PAELLA.pdf\/\"><img decoding=\"async\" class=\"alignnone wp-image-875\" src=\"https:\/\/labarraca1912.es\/wp-content\/uploads\/2019\/08\/icon-folder-300x300.png\" alt=\"\" width=\"21\" height=\"21\" srcset=\"https:\/\/labarraca1912.es\/wp-content\/uploads\/2019\/08\/icon-folder-300x300.png 300w, https:\/\/labarraca1912.es\/wp-content\/uploads\/2019\/08\/icon-folder-150x150.png 150w, https:\/\/labarraca1912.es\/wp-content\/uploads\/2019\/08\/icon-folder-100x100.png 100w, https:\/\/labarraca1912.es\/wp-content\/uploads\/2019\/08\/icon-folder.png 739w\" sizes=\"(max-width: 21px) 100vw, 21px\" \/>\u00a0<span style=\"color: #ad9115;\"><strong>Technical Sheet<\/strong><\/span><\/a><\/h3>\n<div class='et-learn-more clearfix'>\n\t\t\t\t\t<h3 class='heading-more'>Formats<span class='et_learnmore_arrow'><span><\/span><\/span><\/h3>\n\t\t\t\t\t<div class='learn-more-content'>Glass Jar<\/div>\n\t\t\t\t<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"featured_media":2468,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[22,122],"product_tag":[39,35,38,70,41,36,37],"class_list":{"0":"post-2467","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sazonadores","7":"product_cat-productos-paella","8":"product_tag-arroz","9":"product_tag-azafran","10":"product_tag-colorante","11":"product_tag-conejo","12":"product_tag-gazpachos","13":"product_tag-paella","14":"product_tag-saffron","16":"first","17":"outofstock","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sazonador Paella 37g - La Barraca<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/labarraca1912.es\/en\/tienda\/sazonadores\/sazonador-paella-37g\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sazonador Paella 37g - La Barraca\" \/>\n<meta property=\"og:description\" content=\"Sazonador Paella 37g  El Sazonador Paella es un magn\u00edfico producto para darle el sabor ideal a una paella. Gracias a la combinaci\u00f3n de diferentes tipos de especias, hierbas y condimentos, que combinadas hacen de este sazonador indispensable en la elaboraci\u00f3n de una paella. Sazonador compuesto por una mezcla de especias molidas; formulado expresamente para la elaboraci\u00f3n de paellas y arroces. \u00a0Ficha T\u00e9cnica   &nbsp;  &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/labarraca1912.es\/en\/tienda\/sazonadores\/sazonador-paella-37g\/\" \/>\n<meta property=\"og:site_name\" content=\"La Barraca\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-21T10:49:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/labarraca1912.es\/wp-content\/uploads\/2019\/10\/sazonadorpaellacristal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/labarraca1912.es\\\/tienda\\\/sazonadores\\\/sazonador-paella-37g\\\/\",\"url\":\"https:\\\/\\\/labarraca1912.es\\\/tienda\\\/sazonadores\\\/sazonador-paella-37g\\\/\",\"name\":\"Sazonador Paella 37g - La Barraca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/labarraca1912.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/labarraca1912.es\\\/tienda\\\/sazonadores\\\/sazonador-paella-37g\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/labarraca1912.es\\\/tienda\\\/sazonadores\\\/sazonador-paella-37g\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/labarraca1912.es\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/sazonadorpaellacristal.jpg\",\"datePublished\":\"2019-10-03T09:28:17+00:00\",\"dateModified\":\"2022-11-21T10:49:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/labarraca1912.es\\\/tienda\\\/sazonadores\\\/sazonador-paella-37g\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/labarraca1912.es\\\/tienda\\\/sazonadores\\\/sazonador-paella-37g\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/labarraca1912.es\\\/tienda\\\/sazonadores\\\/sazonador-paella-37g\\\/#primaryimage\",\"url\":\"https:\\\/\\\/labarraca1912.es\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/sazonadorpaellacristal.jpg\",\"contentUrl\":\"https:\\\/\\\/labarraca1912.es\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/sazonadorpaellacristal.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/labarraca1912.es\\\/tienda\\\/sazonadores\\\/sazonador-paella-37g\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"La Barraca\",\"item\":\"https:\\\/\\\/labarraca1912.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/labarraca1912.es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sazonador Paella 37g\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/labarraca1912.es\\\/#website\",\"url\":\"https:\\\/\\\/labarraca1912.es\\\/\",\"name\":\"La Barraca\",\"description\":\"La Casa del Sabor\",\"publisher\":{\"@id\":\"https:\\\/\\\/labarraca1912.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/labarraca1912.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/labarraca1912.es\\\/#organization\",\"name\":\"La Barraca 1912 Alimentacion\",\"url\":\"https:\\\/\\\/labarraca1912.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/labarraca1912.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/labarraca1912.es\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-labarraca.png\",\"contentUrl\":\"https:\\\/\\\/labarraca1912.es\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-labarraca.png\",\"width\":2917,\"height\":1809,\"caption\":\"La Barraca 1912 Alimentacion\"},\"image\":{\"@id\":\"https:\\\/\\\/labarraca1912.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sazonador Paella 37g - La Barraca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/labarraca1912.es\/en\/tienda\/sazonadores\/sazonador-paella-37g\/","og_locale":"en_GB","og_type":"article","og_title":"Sazonador Paella 37g - La Barraca","og_description":"Sazonador Paella 37g  El Sazonador Paella es un magn\u00edfico producto para darle el sabor ideal a una paella. Gracias a la combinaci\u00f3n de diferentes tipos de especias, hierbas y condimentos, que combinadas hacen de este sazonador indispensable en la elaboraci\u00f3n de una paella. Sazonador compuesto por una mezcla de especias molidas; formulado expresamente para la elaboraci\u00f3n de paellas y arroces. \u00a0Ficha T\u00e9cnica   &nbsp;  &nbsp;","og_url":"https:\/\/labarraca1912.es\/en\/tienda\/sazonadores\/sazonador-paella-37g\/","og_site_name":"La Barraca","article_modified_time":"2022-11-21T10:49:44+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/labarraca1912.es\/wp-content\/uploads\/2019\/10\/sazonadorpaellacristal.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/labarraca1912.es\/tienda\/sazonadores\/sazonador-paella-37g\/","url":"https:\/\/labarraca1912.es\/tienda\/sazonadores\/sazonador-paella-37g\/","name":"Sazonador Paella 37g - La Barraca","isPartOf":{"@id":"https:\/\/labarraca1912.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/labarraca1912.es\/tienda\/sazonadores\/sazonador-paella-37g\/#primaryimage"},"image":{"@id":"https:\/\/labarraca1912.es\/tienda\/sazonadores\/sazonador-paella-37g\/#primaryimage"},"thumbnailUrl":"https:\/\/labarraca1912.es\/wp-content\/uploads\/2019\/10\/sazonadorpaellacristal.jpg","datePublished":"2019-10-03T09:28:17+00:00","dateModified":"2022-11-21T10:49:44+00:00","breadcrumb":{"@id":"https:\/\/labarraca1912.es\/tienda\/sazonadores\/sazonador-paella-37g\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/labarraca1912.es\/tienda\/sazonadores\/sazonador-paella-37g\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/labarraca1912.es\/tienda\/sazonadores\/sazonador-paella-37g\/#primaryimage","url":"https:\/\/labarraca1912.es\/wp-content\/uploads\/2019\/10\/sazonadorpaellacristal.jpg","contentUrl":"https:\/\/labarraca1912.es\/wp-content\/uploads\/2019\/10\/sazonadorpaellacristal.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/labarraca1912.es\/tienda\/sazonadores\/sazonador-paella-37g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"La Barraca","item":"https:\/\/labarraca1912.es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/labarraca1912.es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Sazonador Paella 37g"}]},{"@type":"WebSite","@id":"https:\/\/labarraca1912.es\/#website","url":"https:\/\/labarraca1912.es\/","name":"La Barraca","description":"La Casa del Sabor","publisher":{"@id":"https:\/\/labarraca1912.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/labarraca1912.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/labarraca1912.es\/#organization","name":"La Barraca 1912 Alimentacion","url":"https:\/\/labarraca1912.es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/labarraca1912.es\/#\/schema\/logo\/image\/","url":"https:\/\/labarraca1912.es\/wp-content\/uploads\/2019\/06\/logo-labarraca.png","contentUrl":"https:\/\/labarraca1912.es\/wp-content\/uploads\/2019\/06\/logo-labarraca.png","width":2917,"height":1809,"caption":"La Barraca 1912 Alimentacion"},"image":{"@id":"https:\/\/labarraca1912.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/labarraca1912.es\/en\/wp-json\/wp\/v2\/product\/2467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/labarraca1912.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/labarraca1912.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/labarraca1912.es\/en\/wp-json\/wp\/v2\/comments?post=2467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/labarraca1912.es\/en\/wp-json\/wp\/v2\/media\/2468"}],"wp:attachment":[{"href":"https:\/\/labarraca1912.es\/en\/wp-json\/wp\/v2\/media?parent=2467"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/labarraca1912.es\/en\/wp-json\/wp\/v2\/product_brand?post=2467"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/labarraca1912.es\/en\/wp-json\/wp\/v2\/product_cat?post=2467"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/labarraca1912.es\/en\/wp-json\/wp\/v2\/product_tag?post=2467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}